{"id":2294,"date":"2020-03-06T16:47:40","date_gmt":"2020-03-06T15:47:40","guid":{"rendered":"https:\/\/vintage-motors.net\/magazine\/?p=2294"},"modified":"2020-03-09T10:48:42","modified_gmt":"2020-03-09T09:48:42","slug":"decouvrez-la-marque-schuberth","status":"publish","type":"post","link":"https:\/\/vintage-motors.net\/magazine\/decouvrez-la-marque-schuberth\/","title":{"rendered":"D\u00e9couvrez la marque Schuberth"},"content":{"rendered":"<h2><span style=\"font-weight: 400;\"><strong><a href=\"https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/C4_PRO_3.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-2301\" src=\"https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/C4_PRO_3.jpg\" alt=\"\" width=\"6000\" height=\"4000\" srcset=\"https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/C4_PRO_3.jpg 6000w, https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/C4_PRO_3-300x200.jpg 300w, https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/C4_PRO_3-768x512.jpg 768w, https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/C4_PRO_3-1024x683.jpg 1024w, https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/C4_PRO_3-900x600.jpg 900w, https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/C4_PRO_3-1280x853.jpg 1280w\" sizes=\"(max-width: 6000px) 100vw, 6000px\" \/><\/a><\/strong><\/span><\/h2>\n<h2><strong>L&rsquo;historique de\u00a0Schuberth<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">La marque allemande est pr\u00e9sente sur le march\u00e9 de la protection de la t\u00eate depuis plus de 90 ans. <strong>Schuberth a d\u00e9but\u00e9 son commerce de casque en 1929<\/strong>, lorsque l\u2019entreprise a fait breveter un savoir-faire de rev\u00eatement en cuir pour les casques des militaires. Puis au fil des ann\u00e9es, la marque a \u00e9tendu ses horizons en travaillant sur les casques des pompiers, de police et de l\u2019industrie mini\u00e8re. Le premier casque de moto a ainsi vu le jour en 1954, avant de voir le premier casque int\u00e9gral en 1976.<br \/>\n<\/span><span style=\"font-weight: 400;\">Depuis ses d\u00e9buts, Schuberth met un point d\u2019honneur \u00e0 offrir la meilleure qualit\u00e9 possible \u00e0 ses produits, mais surtout, \u00e0 perp\u00e9tuer <strong>un savoir-faire enti\u00e8re \u00e0 la main, pendant chaque \u00e9tape du processus de fabrication<\/strong>. Aujourd\u2019hui, l\u2019entreprise allemande ne compte pas moins de quatre cents employ\u00e9s et s\u2019exporte dans plus d\u2019une cinquantaine de pays. Sur place, les ing\u00e9nieurs peaufinent les technologies actuelles tout en mettant au point celles de demain. Les casques sont test\u00e9s et perfectionn\u00e9s en direct, sur le banc climatique ou dans le laboratoire acoustique afin que votre futur casque de moto soit parfait dans les moindres d\u00e9tails. L\u2019entreprise poss\u00e8de m\u00eame sa propre soufflerie.<br \/>\n<\/span><span style=\"font-weight: 400;\"><strong>En 2000, Schuberth s\u2019invite sur les circuits de Formule 1 et continue son ascension et \u00e9tant couronn\u00e9 sur le podium l\u2019ann\u00e9e suivante gr\u00e2ce \u00e0 Michael Schumacher.<\/strong> En 2010, l\u2019entreprise s\u2019importe aussi aux Etats-Unis pour satisfaire le march\u00e9 grandissant am\u00e9ricain. Enfin, en 2019, Schuberth est consacr\u00e9 \u201cmeilleure marque dans la cat\u00e9gorie casque\u201d pour la 14e fois cons\u00e9cutive par le magazine MOTORRAD. La m\u00eame ann\u00e9e, la marque avait mis sur le march\u00e9 son<strong> C4 PRO CARBON, le premier casque modulable avec une coque ext\u00e9rieure en carbone et un syst\u00e8me de communication int\u00e9gr\u00e9.<\/strong><br \/>\n<\/span><\/p>\n<div id=\"attachment_2319\" style=\"width: 639px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/C4-PRO-MAGNITUDO-WHITE-WOMEN.jpg\"><img aria-describedby=\"caption-attachment-2319\" decoding=\"async\" loading=\"lazy\" class=\"size-large wp-image-2319\" src=\"https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/C4-PRO-MAGNITUDO-WHITE-WOMEN-1024x683.jpg\" alt=\"\" width=\"629\" height=\"420\" srcset=\"https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/C4-PRO-MAGNITUDO-WHITE-WOMEN-1024x683.jpg 1024w, https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/C4-PRO-MAGNITUDO-WHITE-WOMEN-300x200.jpg 300w, https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/C4-PRO-MAGNITUDO-WHITE-WOMEN-768x512.jpg 768w, https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/C4-PRO-MAGNITUDO-WHITE-WOMEN-900x600.jpg 900w, https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/C4-PRO-MAGNITUDO-WHITE-WOMEN-1280x853.jpg 1280w, https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/C4-PRO-MAGNITUDO-WHITE-WOMEN.jpg 2048w\" sizes=\"(max-width: 629px) 100vw, 629px\" \/><\/a><p id=\"caption-attachment-2319\" class=\"wp-caption-text\">C4 PRO MAGNITUDO WHITE WOMEN<\/p><\/div>\n<h2><strong>Pr\u00e9sentation des casques Schuberth\u00a0<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Aujourd\u2019hui chez <a href=\"https:\/\/vintage-motors.net\/\">Vintage Motors<\/a>, nous proposons plusieurs mod\u00e8les de casques sign\u00e9s par cette grande marque : du casque int\u00e9gral ou casque jet, au casque modulable, en passant par toutes les nouvelles technologies de pointe pour vous assurer la meilleure protection sur votre deux roues, aussi bien en moto ou scooter.<br \/>\n<\/span><span style=\"font-weight: 400;\">Les casques modulables propos\u00e9s sont des casques urbains ou adapt\u00e9s au touring. <strong>Les casques de la gamme C4 sont un tr\u00e8s bon exemple de casque urbain modulable<\/strong> : <a href=\"https:\/\/vintage-motors.net\/schuberth-m-29\/s-3\/cat%C3%A9gories_2-casque_moto\/fabricant_2-schuberth\">le C4 Pro<\/a>, contrairement au C4 Basic, n\u2019est pas pr\u00e9-\u00e9quip\u00e9 du syst\u00e8me intercom de la marque (\u00e0 savoir les \u00e9couteurs et le micro d\u00e9j\u00e0 int\u00e9gr\u00e9s). N\u00e9anmoins, il \u00e9tait possible de les rajouter en option au moment de l\u2019achat.\u00a0<\/span><span style=\"font-weight: 400;\">Concernant les mod\u00e8les touring, le casque E1 est un bon exemple de casque modulable propos\u00e9 par Schuberth et il a la particularit\u00e9 d\u2019avoir une visi\u00e8re solaire int\u00e9gr\u00e9e.<br \/>\n<\/span><span style=\"font-weight: 400;\">Enfin, pour les casques int\u00e9graux, la plus grande majorit\u00e9 sont des casques sportifs, notamment comme le c\u00e9l\u00e8bre R2 ou le SR2, \u00e0 l\u2019utilisation et aux courbes typiquement sportives. Le S2 quant \u00e0 lui, jongle avec les codes en \u00e9tant un alliage entre un mi-sport (gr\u00e2ce \u00e0 sa visi\u00e8re solaire qui assure un champ de vision optimal) et un mi-urbain.<br \/>\n<\/span><\/p>\n<div id=\"attachment_2321\" style=\"width: 660px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/CASQUE-SR2-ECE-MATT-BLACK.jpg\"><img aria-describedby=\"caption-attachment-2321\" decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-2321\" src=\"https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/CASQUE-SR2-ECE-MATT-BLACK.jpg\" alt=\"\" width=\"650\" height=\"650\" srcset=\"https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/CASQUE-SR2-ECE-MATT-BLACK.jpg 650w, https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/CASQUE-SR2-ECE-MATT-BLACK-150x150.jpg 150w, https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/CASQUE-SR2-ECE-MATT-BLACK-300x300.jpg 300w, https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/CASQUE-SR2-ECE-MATT-BLACK-88x88.jpg 88w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/a><p id=\"caption-attachment-2321\" class=\"wp-caption-text\">CASQUE SR2 ECE MATT BLACK<\/p><\/div>\n<p><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Schuberth a notamment su s\u2019imposer sur le march\u00e9 du casque moto avec d\u2019excellentes performances d\u2019insonorisation, une qualit\u00e9 particuli\u00e8rement pris\u00e9e en ville et sur les circuits.<strong> Bien choisir son casque est important pour votre s\u00e9curit\u00e9, mais \u00e9galement pour que votre \u00e9quipement moto soit le plus confortable possible.<\/strong> Souvent, les motards ont reproch\u00e9 \u00e0 la marque allemande de pr\u00e9f\u00e9rer les performances au confort. Ce d\u00e9faut a \u00e9t\u00e9 amplement corrig\u00e9 lors de la sortie du C4Pro, avec un int\u00e9rieur bien plus doux et confortable que ses pr\u00e9d\u00e9cesseurs.<br \/>\n<\/span><span style=\"font-weight: 400;\">De plus<strong>, les casques de moto Schuberth sont adapt\u00e9s pour tous les looks, mais \u00e9galement tous les styles de conduite<\/strong>, que vous utilisiez votre deux-roues, pour une conduite citadine de la vie de tous les jours, ou plus sportive. Routiers ou sportifs, homme ou femme, vous trouverez votre bonheur dans la vari\u00e9t\u00e9 de gamme propos\u00e9e.\u00a0<\/span><span style=\"font-weight: 400;\">C\u00f4t\u00e9 mat\u00e9riaux, <strong>la marque est connue pour ses compositions uniquement en fibres de verre ou en carbone.<\/strong><br \/>\n<\/span><span style=\"font-weight: 400;\">En terme de rapport qualit\u00e9 prix, Schuberth a rapidement su s\u2019imposer sur le march\u00e9 du casque moto et automobile.\u00a0<\/span><\/p>\n<h2><strong>Les produits embl\u00e9matiques<\/strong><\/h2>\n<ul>\n<li><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\"><strong>Le C4 PRO CARBON<\/strong><br \/>\n<\/span><\/span><\/p>\n<p><div id=\"attachment_2299\" style=\"width: 2058px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/20191006_134727_IMG_0717.jpg\"><img aria-describedby=\"caption-attachment-2299\" decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-2299\" src=\"https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/20191006_134727_IMG_0717.jpg\" alt=\"\" width=\"2048\" height=\"1365\" srcset=\"https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/20191006_134727_IMG_0717.jpg 2048w, https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/20191006_134727_IMG_0717-300x200.jpg 300w, https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/20191006_134727_IMG_0717-768x512.jpg 768w, https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/20191006_134727_IMG_0717-1024x683.jpg 1024w, https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/20191006_134727_IMG_0717-900x600.jpg 900w, https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/20191006_134727_IMG_0717-1280x853.jpg 1280w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/a><p id=\"caption-attachment-2299\" class=\"wp-caption-text\">C4 PRO MAGNITUDO WHITE<\/p><\/div><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Le C4Pro Carbon est le dernier casque d\u00e9voil\u00e9 par la marque allemande.<strong> Le C4 Pro Carbon est le casque le plus vendu de la marque aujourd\u2019hui : c\u2019est un casque haut-de-gamme pour les motards GT, \u00e0 la recherche d\u2019une protection aussi l\u00e9g\u00e8re que qualitative, aux finitions agr\u00e9ables et \u00e0 l\u2019insonorit\u00e9 agr\u00e9able.<\/strong><br \/>\n<\/span><span style=\"font-weight: 400;\">C\u2019est un petit bijou de technologie qui d\u00e9coule d\u2019un savant m\u00e9lange entre le confort d\u2019un casque modulable et la l\u00e9g\u00e8ret\u00e9 d\u2019une coque ext\u00e9rieure en carbone, notamment utilis\u00e9 sur les pistes de Formule 1. <strong>C\u2019est le tout premier casque modulable en carbone dont l\u2019intercom est d\u00e9j\u00e0 int\u00e9gr\u00e9e<\/strong>. Il contient notamment une antenne int\u00e9gr\u00e9e, des hauts-parleurs pr\u00e9install\u00e9s et un microphone pr\u00e9 install\u00e9 pour une r\u00e9ception Bluetooth et une radio optimale.<br \/>\n<\/span><span style=\"font-weight: 400;\">Il est \u00e9galement \u00e9quip\u00e9 d\u2019<a href=\"https:\/\/vintage-motors.net\/schuberth-m-29\/s-3\/cat%C3%A9gories_2-visieres_moto\/fabricant_2-schuberth\">une visi\u00e8re anti-bu\u00e9e \u00e0 \u00e9cran large Pinlock<\/a>. La visi\u00e8re pinlock r\u00e9siste aux rayures. Un pare-soleil automatique est int\u00e9gr\u00e9 et se r\u00e8gle tout seul en continu en seulement quelques secondes. A l\u2019int\u00e9rieur, la marque innove encore une fois, avec un tout nouveau concept acoustique gr\u00e2ce \u00e0 un rembourrage optimis\u00e9 au niveau de la nuque. Cela augmente la r\u00e9duction de bruits. L\u2019ensemble est confortable et petit bonus tr\u00e8s appr\u00e9ci\u00e9 et appr\u00e9ciable :<strong> ils sont fabriqu\u00e9s sans coutures et comptent un espace pour les personnes qui portent des lunettes.<\/strong> Au final, le C4 Pro Carbon affiche un joli bilan avec environ 85 dB(A) \u00e0 100km\/h.<br \/>\n<\/span><span style=\"font-weight: 400;\">Sur ce mod\u00e8le, on trouvera \u00e9galement sur des rev\u00eatements int\u00e9rieurs confortables et un \u00e9quipement Coolmax d\u00e9tachable et lavable.<strong> La coque int\u00e9rieure est donc constitu\u00e9e de plusieurs couches de mousses diff\u00e9rentes pour permettre une absorption extr\u00eame des chocs<\/strong>. La version ant\u00e9rieure (le C4) avait suscit\u00e9 d\u00e9bat sur le positionnement de son syst\u00e8me d\u2019intercom situ\u00e9 sur le haut du casque. La marque a su \u00e9couter les remarques des motards a corrig\u00e9 le tir sur le mod\u00e8le C4 Pro en int\u00e9grant le syst\u00e8me dans la pi\u00e8ce de la joue : le son est d\u00e9sormais meilleur et \u00e9touffe davantage les parasites li\u00e9s au vent. Enfin, la circulation de l\u2019air est optimale gr\u00e2ce \u00e0 une a\u00e9ration multi-canal.<br \/>\n<\/span><span style=\"font-weight: 400;\"><strong>Le C4 Pro existe aussi pour les femmes<\/strong>, qui dispose de mousses de joues suppl\u00e9mentaires pour s\u2019adapter aux morphologies de visage pour fines.<br \/>\n<\/span><\/p>\n<div id=\"attachment_2297\" style=\"width: 2058px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/20191005_123659_IMG_0064.jpg\"><img aria-describedby=\"caption-attachment-2297\" decoding=\"async\" loading=\"lazy\" class=\"wp-image-2297 size-full\" src=\"https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/20191005_123659_IMG_0064.jpg\" alt=\"\" width=\"2048\" height=\"1365\" srcset=\"https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/20191005_123659_IMG_0064.jpg 2048w, https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/20191005_123659_IMG_0064-300x200.jpg 300w, https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/20191005_123659_IMG_0064-768x512.jpg 768w, https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/20191005_123659_IMG_0064-1024x683.jpg 1024w, https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/20191005_123659_IMG_0064-900x600.jpg 900w, https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/20191005_123659_IMG_0064-1280x853.jpg 1280w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/a><p id=\"caption-attachment-2297\" class=\"wp-caption-text\">C4 PRO MAGNITUDO YELLOW<\/p><\/div>\n<p><span style=\"font-weight: 400;\">Au final, cette gamme est constitu\u00e9e, par ordre chronologique :<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">_<strong> Le C4<\/strong> est sorti en premier, c\u2019est une entr\u00e9e de gamme. C\u2019est un casque modulable en fibres, pr\u00e9par\u00e9 aux kits intercoms avec un micro dans la joue. Il existe en noir brillant et en blanc brillant.<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">_ <strong><a href=\"https:\/\/vintage-motors.net\/casque-c4-pro-carbon-ece-fusion-white-schuberth-p-10729.html#\/2-taille-xs\/105-famille_de_couleur-d%C3%A9co\/164-couleur-noir_blanc\">Le C4 Pro<\/a><\/strong> est la version am\u00e9lior\u00e9e de son pr\u00e9d\u00e9cesseur. L\u2019emplacement de l\u2019intercom a \u00e9t\u00e9 modifi\u00e9. Sur le C4, il \u00e9tait situ\u00e9 en haut du casque, sur le C4Pro, il a \u00e9t\u00e9 d\u00e9plac\u00e9 dans les joues. L\u2019int\u00e9rieur a \u00e9galement \u00e9t\u00e9 modifi\u00e9, rendant le tout plus doux et surtout plus confortable.<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">_ <a href=\"https:\/\/vintage-motors.net\/casque-c4-basic-ece-matt-black-schuberth-p-10756.html#\/2-taille-xs\/55-couleur-noir_mat\/104-famille_de_couleur-noir\"><strong>Le C4 Basic<\/strong><\/a> ressemble au C4 Pro, sauf qu\u2019il n\u2019est pas pr\u00e9par\u00e9 pour l\u2019intercom. Il est disponible en trois coloris : en Matt Black, en Glossy Silver et en Glossy White. D&rsquo;autres d\u00e9clinaisons existent.<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Ces mod\u00e8les sont compatibles avec les intercoms suivantes : <strong>SC1 Standard et SC1 Advanced. <\/strong><\/span><\/p>\n<div id=\"attachment_2312\" style=\"width: 670px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/SC1_ADVANCED-1.png\"><img aria-describedby=\"caption-attachment-2312\" decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-2312\" src=\"https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/SC1_ADVANCED-1.png\" alt=\"\" width=\"660\" height=\"765\" srcset=\"https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/SC1_ADVANCED-1.png 660w, https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/SC1_ADVANCED-1-259x300.png 259w\" sizes=\"(max-width: 660px) 100vw, 660px\" \/><\/a><p id=\"caption-attachment-2312\" class=\"wp-caption-text\">INTERCOM SC1 ADVANCED<\/p><\/div>\n<p><span style=\"font-weight: 400;\">_ <strong>Le <a href=\"https:\/\/vintage-motors.net\/casque-c4-pro-carbon-ece-fusion-white-schuberth-p-10729.html#\/2-taille-xs\/105-famille_de_couleur-d%C3%A9co\/164-couleur-noir_blanc\">C4Pro Carbon<\/a> <\/strong>est la version haut de gamme des casques pr\u00e9c\u00e9dents, dont nous vous avons parl\u00e9 ci-dessus.\u00a0<\/span><\/p>\n<p>[metaslider id=2311]<\/p>\n<ul>\n<li><span style=\"font-weight: 400;\"><strong>Le M1PRO<\/strong><br \/>\n<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\"><a href=\"https:\/\/vintage-motors.net\/casque-m1-pro-ece-matt-black-schuberth-p-10746.html#\/2-taille-xs\/55-couleur-noir_mat\/104-famille_de_couleur-noir\">Le M1Pro<\/a> est le casque jet embl\u00e9matique de la marque allemande. Il est \u00e9quip\u00e9 d\u2019une visi\u00e8re solaire, mais \u00e9galement d\u2019<strong>une visi\u00e8re claire qui descend jusqu\u2019au bas du visage<\/strong> : un d\u00e9tail particuli\u00e8rement agr\u00e9able en toutes saisons qui prot\u00e8ge particuli\u00e8rement bien son motard. Ce mod\u00e8le poss\u00e8de une ventilation cons\u00e9quente sur le dessus du casque, qui lui permet une ventilation optimale. Elle est cependant avec clapet et donc refermable. Le reste du casque a \u00e9t\u00e9 con\u00e7u pour que l\u2019air circule parfaitement gr\u00e2ce \u00e0 des canaux de ventilation int\u00e9gr\u00e9s directement dans le reste du casque. Il reste l\u00e9ger dans son ensemble : le plus petit mod\u00e8le commence \u00e0 1.450kg. Les mousses des joues, comme tous les Schuberth sont d\u00e9montables et lavables.<br \/>\n<\/span><span style=\"font-weight: 400;\">Enfin,<strong><a href=\"https:\/\/vintage-motors.net\/casque-m1-pro-ece-matt-black-schuberth-p-10746.html#\/2-taille-xs\/55-couleur-noir_mat\/104-famille_de_couleur-noir\"> le M1Pro<\/a> est pr\u00e9par\u00e9 au pinlock et \u00e0 <a href=\"https:\/\/vintage-motors.net\/kit-src-bluetooth-integre-pour-schuberth-m1-p-846.html#\/18-couleur-noir\/56-taille-unique\">l\u2019intercom<\/a><\/strong>. Il est compatible avec les mod\u00e8les SC1M et SRCM1.\u00a0<\/span><span style=\"font-weight: 400;\">Il est disponible dans de nombreuses d\u00e9clinaisons de couleurs :<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">_ dans les couleurs basiques, Schuberth propose du blanc brillant et du noir matt (\u00e0 439\u20ac),<br \/>\n<\/span><span style=\"font-weight: 400;\">_ et dans les couleurs graphiques, le M1Pro dispose de : strike black, triple yellow, triple red, outline red, outline grey et outline black (pour 539\u20ac).<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Le M1Pro existe de la taille XS au XXL.\u00a0<\/span><\/p>\n<div id=\"attachment_2305\" style=\"width: 670px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/M1PRO-Outline-Black.png\"><img aria-describedby=\"caption-attachment-2305\" decoding=\"async\" loading=\"lazy\" class=\"wp-image-2305 size-full\" src=\"https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/M1PRO-Outline-Black.png\" alt=\"\" width=\"660\" height=\"632\" srcset=\"https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/M1PRO-Outline-Black.png 660w, https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/M1PRO-Outline-Black-300x287.png 300w\" sizes=\"(max-width: 660px) 100vw, 660px\" \/><\/a><p id=\"caption-attachment-2305\" class=\"wp-caption-text\">M1 PRO-Outline Black<\/p><\/div>\n<ul>\n<li><strong>Le E1<\/strong><\/li>\n<\/ul>\n<p><strong>Le E1 de Schuberth est le casque Adventure embl\u00e9matique de la marque.<\/strong> Il a le confort d&rsquo;un modulable tout en abordant un aspect \u00ab\u00a0Look &amp; Feel\u00a0\u00bb.\u00a0 Ce casque innovant Dualsport est parfaitement adapt\u00e9 pour les motards d\u2019enduro et d\u2019adventure bike. Il offre le maximum de flexibilit\u00e9 et de s\u00e9curit\u00e9 pour l\u2019usage tant on que off-road. L&rsquo;ensemble de la circulation de l&rsquo;air a \u00e9t\u00e9 pens\u00e9 pour que l&rsquo;air se r\u00e9partisse aussi \u00e0 l&rsquo;int\u00e9rieur du casque.\u00a0L\u2019a\u00e9ration de la visi\u00e8re quant \u00e0 elle, \u00e9vite et pr\u00e9vient la formation de bu\u00e9e sur l\u2019\u00e9cran. L&rsquo;a\u00e9ration est \u00e9galement r\u00e9glable au niveau du menton pour am\u00e9liorer votre respiration.\u00a0Un \u00e9cran solaire est int\u00e9gr\u00e9 dans ce mod\u00e8le. Il peut \u00eatre rentr\u00e9 et sorti en d\u00e9pla\u00e7ant un petit curseur situ\u00e9 au bord du casque d\u2019un simple mouvement de la main. En cas de contre-jour notamment, vous pouvez r\u00e9agir instantan\u00e9ment.<\/p>\n<div id=\"attachment_2334\" style=\"width: 670px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/E1-Cut-Blue-90_5314370e08.png\"><img aria-describedby=\"caption-attachment-2334\" decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-2334\" src=\"https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/E1-Cut-Blue-90_5314370e08.png\" alt=\"\" width=\"660\" height=\"561\" srcset=\"https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/E1-Cut-Blue-90_5314370e08.png 660w, https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/E1-Cut-Blue-90_5314370e08-300x255.png 300w\" sizes=\"(max-width: 660px) 100vw, 660px\" \/><\/a><p id=\"caption-attachment-2334\" class=\"wp-caption-text\">Schuberth E1<\/p><\/div>\n<h2><strong>Les protections<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Les casques Schuberth sont \u00e9quip\u00e9s de plusieurs fermetures selon les mod\u00e8les, exclusivement en boucle microm\u00e9trique. Selon le casque que vous choisissez, le maintien sur votre menton et la prise sur votre jugulaire seront diff\u00e9rents. La protection et le confort ne seront pas les m\u00eames. Faites votre choix en fonction de vos pr\u00e9f\u00e9rences et de votre utilisation de votre deux roues. Le casque R2 Sport par exemple, poss\u00e8de une fermeture double D. La mentonni\u00e8re d\u00e9pendra du type de casque que vous choisissez : int\u00e9gral ou modulable. Sur tous les mod\u00e8les,<\/span><span style=\"font-weight: 400;\">\u00a0la mousse de protection \u00e0 l\u2019int\u00e9rieur des joues est d\u00e9tachable et lavable.<br \/>\n<\/span><span style=\"font-weight: 400;\">Avant d\u2019acheter un casque de moto, <strong>pensez \u00e0 mesurer votre tour de t\u00eate ou \u00e0 demander directement en magasin<\/strong> afin de prendre la meilleure taille pour vous. Il en est de m\u00eame pour un casque moto femme et pour un casque moto enfant. Prendre la bonne taille vous assure confort, mais surtout un maximum de s\u00e9curit\u00e9.<\/span><\/p>\n<h2><strong>Les \u00e9quipements\u00a0<\/strong><\/h2>\n<div id=\"attachment_2299\" style=\"width: 639px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/20191006_134727_IMG_0717.jpg\"><img aria-describedby=\"caption-attachment-2299\" decoding=\"async\" loading=\"lazy\" class=\"wp-image-2299 size-large\" src=\"https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/20191006_134727_IMG_0717-1024x683.jpg\" alt=\"\" width=\"629\" height=\"420\" srcset=\"https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/20191006_134727_IMG_0717-1024x683.jpg 1024w, https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/20191006_134727_IMG_0717-300x200.jpg 300w, https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/20191006_134727_IMG_0717-768x512.jpg 768w, https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/20191006_134727_IMG_0717-900x600.jpg 900w, https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/20191006_134727_IMG_0717-1280x853.jpg 1280w, https:\/\/vintage-motors.net\/magazine\/wp-content\/uploads\/2020\/03\/20191006_134727_IMG_0717.jpg 2048w\" sizes=\"(max-width: 629px) 100vw, 629px\" \/><\/a><p id=\"caption-attachment-2299\" class=\"wp-caption-text\">C4 PRO MAGNITUDO WHITE<\/p><\/div>\n<p><span style=\"font-weight: 400;\">Vos casques Schuberth peuvent se compl\u00e9ter avec un pinlock (\u00e0 fixer gr\u00e2ce \u00e0 des picots sur le c\u00f4t\u00e9). Ainsi votre visi\u00e8re sera \u00e9quip\u00e9e d\u2019une protection antibu\u00e9e et vous pourrez rouler en toute s\u00e9curit\u00e9, par tous les temps. En revanche, le casque C36PRO lui, est \u00e9quip\u00e9 d\u2019une visi\u00e8re anti-rayures en polycarbonate. Sachez que les visi\u00e8res que vous pr\u00e9f\u00e9rez ne sont pas toutes compatibles avec un pinlock : pensez \u00e0 v\u00e9rifier.<br \/>\n<\/span><span style=\"font-weight: 400;\">Concernant la ventilation et l\u2019a\u00e9ration, les casques sportifs sont forc\u00e9ment plus ventil\u00e9s que les urbains. Ils poss\u00e8dent g\u00e9n\u00e9ralement des ajouts d\u2019ouverture au niveau de la calotte ext\u00e9rieure pour vous permettre de gagner en vitesse et en a\u00e9rodynamisme lors de vos trajets racing ou en moto cross. Ils sont n\u00e9anmoins plus bruyants, mais <strong>chez Schuberth, les bruits sont plus que raisonnables\u00a0<\/strong>par rapport \u00e0 d&rsquo;autres marques.<br \/>\n<\/span><span style=\"font-weight: 400;\">La marque allemande est \u00e9galement reconnue pour son mat\u00e9riel intercom et ses ajouts d\u2019accessoires connect\u00e9s via bluetooth.<br \/>\n<\/span><\/p>\n<h2><strong>Garantie et relation client<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">La relation client est \u00e9galement au c\u0153ur de la politique de Schuberth. Sur le site internet, vous pouvez enregistrer les informations concernant votre casque et vous saurez s\u2019il est toujours sous garantie. La garantie elle, est de cinq ans, sans engager de frais suppl\u00e9mentaires, et ce dans le monde entier, sans co\u00fbts suppl\u00e9mentaires et sans aucun subterfuge. En revanche, les conditions de la garantie sont pr\u00e9cises : les traces d&rsquo;utilisation et les dommages survenus suite \u00e0 un usage inappropri\u00e9, \u00e0 un entretien inad\u00e9quat, \u00e0 des transformations ou modifications du casque n&rsquo;entrent pas dans la garantie. Les dommages subis par le casque suite \u00e0 un accident ne sont certes, pas couverts par la garantie et ne peuvent non plus, jamais, faire l&rsquo;objet de r\u00e9parations pour des raisons de s\u00e9curit\u00e9. Cependant,\u00a0<strong>le fabricant propose \u00e0 l&rsquo;accident\u00e9 l&rsquo;achat d&rsquo;un casque du m\u00eame type au tiers du prix recommand\u00e9 \u00e0 titre indicatif au moment de l&rsquo;accident.<\/strong> Une attention et un geste commercial qui sont grandement appr\u00e9ci\u00e9s par les clients.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pensez \u00e9galement \u00e0 \u00e9quiper votre passager d\u2019un bon casque de moto : le conducteur d\u2019une moto ou scooter a aussi la responsabilit\u00e9 de la personne qu\u2019il transporte. Si votre v\u00e9hicule le permet, acheter un casque de moto en plus est une s\u00e9curit\u00e9 appr\u00e9ci\u00e9e.<br \/>\n<\/span><span style=\"font-weight: 400;\">Les casques sont homologu\u00e9s CE. La marque dispose des tailles : taille taille XS, taille S, taille M, taille L, taille XL et taille XXL. Des mod\u00e8les de casques moto pour enfant existent \u00e9galement chez certains fabricants.<\/span><\/p>\n<h2><strong>Compl\u00e9tez votre \u00e9quipement<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Pour des raisons \u00e9videntes de s\u00e9curit\u00e9, votre casque de moto Schuberth ne doit pas \u00eatre l\u2019unique protection sur votre deux roues. Le port des gants moto est obligatoire en toutes saisons \u00e9galement. Un \u00e9quipement motard complet et optimal est vivement recommand\u00e9 pour tous vos trajets, que ce soit des longs trajets ou non.\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;historique de\u00a0Schuberth La marque allemande est pr\u00e9sente sur le march\u00e9 de la protection de la t\u00eate depuis plus de 90 ans. Schuberth a d\u00e9but\u00e9 son commerce de casque en 1929, lorsque l\u2019entreprise a fait breveter un savoir-faire de rev\u00eatement en cuir pour les casques des militaires. Puis au fil des ann\u00e9es, la marque a \u00e9tendu [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2301,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"_links":{"self":[{"href":"https:\/\/vintage-motors.net\/magazine\/wp-json\/wp\/v2\/posts\/2294"}],"collection":[{"href":"https:\/\/vintage-motors.net\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vintage-motors.net\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vintage-motors.net\/magazine\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vintage-motors.net\/magazine\/wp-json\/wp\/v2\/comments?post=2294"}],"version-history":[{"count":21,"href":"https:\/\/vintage-motors.net\/magazine\/wp-json\/wp\/v2\/posts\/2294\/revisions"}],"predecessor-version":[{"id":2335,"href":"https:\/\/vintage-motors.net\/magazine\/wp-json\/wp\/v2\/posts\/2294\/revisions\/2335"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vintage-motors.net\/magazine\/wp-json\/wp\/v2\/media\/2301"}],"wp:attachment":[{"href":"https:\/\/vintage-motors.net\/magazine\/wp-json\/wp\/v2\/media?parent=2294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vintage-motors.net\/magazine\/wp-json\/wp\/v2\/categories?post=2294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vintage-motors.net\/magazine\/wp-json\/wp\/v2\/tags?post=2294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}